{"id":778,"date":"2017-05-03T20:00:05","date_gmt":"2017-05-03T18:00:05","guid":{"rendered":"http:\/\/www.amis-musee-faience-quimper.fr\/?p=778"},"modified":"2017-05-21T10:57:13","modified_gmt":"2017-05-21T08:57:13","slug":"lassemblee-generale-2017","status":"publish","type":"post","link":"http:\/\/www.amis-musee-faience-quimper.fr\/index.php\/2017\/05\/03\/lassemblee-generale-2017\/","title":{"rendered":"L&rsquo;assembl\u00e9e g\u00e9n\u00e9rale 2017."},"content":{"rendered":"<h1 style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-780 aligncenter\" src=\"http:\/\/www.amis-musee-faience-quimper.fr\/wp-content\/uploads\/2017\/05\/AG_AAMFQ_2017_1-300x225.jpg\" alt=\"AG 2017\" width=\"300\" height=\"225\" srcset=\"http:\/\/www.amis-musee-faience-quimper.fr\/wp-content\/uploads\/2017\/05\/AG_AAMFQ_2017_1-300x225.jpg 300w, http:\/\/www.amis-musee-faience-quimper.fr\/wp-content\/uploads\/2017\/05\/AG_AAMFQ_2017_1-400x300.jpg 400w, http:\/\/www.amis-musee-faience-quimper.fr\/wp-content\/uploads\/2017\/05\/AG_AAMFQ_2017_1.jpg 735w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/h1>\n<p>Le samedi 15 avril 2017, s&rsquo;est tenue l&rsquo;assembl\u00e9e g\u00e9n\u00e9rale de l&rsquo;association des Amis du Mus\u00e9e et de la Fa\u00efence de Quimper au sein des locaux de la fa\u00efencerie Henriot-Quimper \u00e0 Locmaria.<\/p>\n<p>Mme Annic Constanty (Vice-Pr\u00e9sidente) menait la r\u00e9union en l&rsquo;absence de M. Jean-Paul Alayse (Pr\u00e9sident).<\/p>\n<p>Le bilan de l&rsquo;ann\u00e9e 2016 et les diff\u00e9rentes activit\u00e9s de l&rsquo;association sont expos\u00e9s par notre secr\u00e9taire Genevi\u00e8ve Pageot.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-781 aligncenter\" src=\"http:\/\/www.amis-musee-faience-quimper.fr\/wp-content\/uploads\/2017\/05\/AG_AAMFQ_2017_2-300x225.jpg\" alt=\"AG 2017\" width=\"300\" height=\"225\" srcset=\"http:\/\/www.amis-musee-faience-quimper.fr\/wp-content\/uploads\/2017\/05\/AG_AAMFQ_2017_2-300x225.jpg 300w, http:\/\/www.amis-musee-faience-quimper.fr\/wp-content\/uploads\/2017\/05\/AG_AAMFQ_2017_2-400x300.jpg 400w, http:\/\/www.amis-musee-faience-quimper.fr\/wp-content\/uploads\/2017\/05\/AG_AAMFQ_2017_2.jpg 735w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Philippe Th\u00e9allet intervient pour pr\u00e9senter les diff\u00e9rentes \u00e9tapes de r\u00e9alisation de <a href=\"http:\/\/www.amis-musee-faience-quimper.fr\/index.php\/category\/expositions\/la-gazette-des-amis\/\">la gazette des Amis<\/a>, qui reste l&rsquo;\u00e9l\u00e9ment de liaison privil\u00e9gi\u00e9 \u00e0 destination des adh\u00e9rents.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-782 aligncenter\" src=\"http:\/\/www.amis-musee-faience-quimper.fr\/wp-content\/uploads\/2017\/05\/AG_AAMFQ_2017_3-300x225.jpg\" alt=\"AG 2017\" width=\"300\" height=\"225\" srcset=\"http:\/\/www.amis-musee-faience-quimper.fr\/wp-content\/uploads\/2017\/05\/AG_AAMFQ_2017_3-300x225.jpg 300w, http:\/\/www.amis-musee-faience-quimper.fr\/wp-content\/uploads\/2017\/05\/AG_AAMFQ_2017_3-400x300.jpg 400w, http:\/\/www.amis-musee-faience-quimper.fr\/wp-content\/uploads\/2017\/05\/AG_AAMFQ_2017_3.jpg 735w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>L&rsquo;association \u00e9dite comme chaque ann\u00e9e le catalogue de l&rsquo;exposition th\u00e9matique 2017 :\u00a0<em>Armor, Argoat \u2013 La Bretagne au travail.<\/em><\/p>\n<p><a href=\"http:\/\/www.amis-musee-faience-quimper.fr\/index.php\/2017\/04\/18\/armor-argoat-la-bretagne-au-travail\/\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-755 aligncenter\" src=\"http:\/\/www.amis-musee-faience-quimper.fr\/wp-content\/uploads\/2017\/04\/couvcat2017web-219x300.jpg\" alt=\"Armor Argoat\" width=\"219\" height=\"300\" srcset=\"http:\/\/www.amis-musee-faience-quimper.fr\/wp-content\/uploads\/2017\/04\/couvcat2017web-219x300.jpg 219w, http:\/\/www.amis-musee-faience-quimper.fr\/wp-content\/uploads\/2017\/04\/couvcat2017web.jpg 469w\" sizes=\"auto, (max-width: 219px) 100vw, 219px\" \/><\/a><\/p>\n<p>Les projets de l&rsquo;ann\u00e9e 2017 seront les suivants :<\/p>\n<ul>\n<li>Les journ\u00e9es Europ\u00e9ennes du Patrimoine, le 16 &amp; 17 septembre 2017. L&rsquo;association animera l\u2019\u00e9v\u00e9nement autour du th\u00e8me : \u00ab\u00a0les femmes artistes\u00a0\u00bb.<\/li>\n<li>Le 40\u00e8me salon des antiquit\u00e9s de Quimper du 10 au 12 novembre 2017, ayant pour th\u00e8me : \u00ab\u00a0la fa\u00efence de Quimper\u00a0\u00bb.<\/li>\n<\/ul>\n<p>Le nouveau site internet de l&rsquo;association est pr\u00e9sent\u00e9 en avant-premi\u00e8re aux adh\u00e9rents, par le biais d&rsquo;une vid\u00e9o-projection.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-783 aligncenter\" src=\"http:\/\/www.amis-musee-faience-quimper.fr\/wp-content\/uploads\/2017\/05\/AG_AAMFQ_2017_4-300x225.jpg\" alt=\"AG 2017\" width=\"300\" height=\"225\" srcset=\"http:\/\/www.amis-musee-faience-quimper.fr\/wp-content\/uploads\/2017\/05\/AG_AAMFQ_2017_4-300x225.jpg 300w, http:\/\/www.amis-musee-faience-quimper.fr\/wp-content\/uploads\/2017\/05\/AG_AAMFQ_2017_4-400x300.jpg 400w, http:\/\/www.amis-musee-faience-quimper.fr\/wp-content\/uploads\/2017\/05\/AG_AAMFQ_2017_4.jpg 735w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Herv\u00e9 Cossec pr\u00e9sente le rapport financier de l&rsquo;association pour l&rsquo;ann\u00e9e \u00e9coul\u00e9e. Il est vivement remerci\u00e9 par le bureau pour l&rsquo;ensemble de son travail. Il est remplac\u00e9 par Patrick Mon\u00e9ger, membre fondateur de l&rsquo;association.<\/p>\n<p>Apr\u00e8s le rapport moral, M. Herv\u00e9 Maupin pr\u00e9sident du fonds de dotation du mus\u00e9e, prend la parole. Il rappelle le r\u00f4le du fonds et remercie l&rsquo;association pour son travail d&rsquo;accompagnement.<\/p>\n<p>Bernard Jules Verlingue, conservateur et directeur du mus\u00e9e de la fa\u00efence de Quimper, d\u00e9voile le th\u00e8me de l&rsquo;exposition de l&rsquo;ann\u00e9e prochaine : Jeanne Malivel (<span style=\"color: #3366ff;\"><a style=\"color: #3366ff;\" href=\"https:\/\/amisjeannemalivel.jimdo.com\/\">site des Amis<\/a><\/span>).<\/p>\n<p>Guenha\u00ebl le Moing est \u00e9lu \u00e0 l&rsquo;unanimit\u00e9 au conseil d&rsquo;administration de l&rsquo;association.<\/p>\n<p><span style=\"color: #3366ff;\"><strong><a style=\"color: #3366ff;\" href=\"http:\/\/www.amis-musee-faience-quimper.fr\/index.php\/adherer\/\">N&rsquo;h\u00e9sitez pas \u00e0 nous rejoindre<\/a>.<\/strong><\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-784 aligncenter\" src=\"http:\/\/www.amis-musee-faience-quimper.fr\/wp-content\/uploads\/2017\/05\/AG_AAMFQ_2017_5-300x169.jpg\" alt=\"AG 2017\" width=\"300\" height=\"169\" srcset=\"http:\/\/www.amis-musee-faience-quimper.fr\/wp-content\/uploads\/2017\/05\/AG_AAMFQ_2017_5-300x169.jpg 300w, http:\/\/www.amis-musee-faience-quimper.fr\/wp-content\/uploads\/2017\/05\/AG_AAMFQ_2017_5-500x281.jpg 500w, http:\/\/www.amis-musee-faience-quimper.fr\/wp-content\/uploads\/2017\/05\/AG_AAMFQ_2017_5.jpg 735w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le samedi 15 avril 2017, s&rsquo;est tenue l&rsquo;assembl\u00e9e g\u00e9n\u00e9rale de l&rsquo;association des Amis du Mus\u00e9e et de la Fa\u00efence de Quimper au sein des locaux de la fa\u00efencerie Henriot-Quimper \u00e0 Locmaria. Mme Annic Constanty (Vice-Pr\u00e9sidente) menait la r\u00e9union en l&rsquo;absence &hellip; <a href=\"http:\/\/www.amis-musee-faience-quimper.fr\/index.php\/2017\/05\/03\/lassemblee-generale-2017\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[17],"tags":[328,348,240,149,340,339,347,102,245,349,350,264,60,351,187,234,262,176,91,15],"class_list":["post-778","post","type-post","status-publish","format-standard","hentry","category-actualites","tag-328","tag-ag","tag-annic-constanty","tag-antoine-maigne","tag-argoat","tag-armor","tag-assemblee","tag-catalogue","tag-daniel-georges","tag-faiencerie","tag-genevieve-pageot","tag-guenhael-le-moing","tag-henriot","tag-herve-cossec","tag-herve-maupin","tag-jean-paul-alayse","tag-malivel","tag-patrick-moneger","tag-theallet","tag-verlingue"],"jetpack_publicize_connections":[],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8tKLp-cy","_links":{"self":[{"href":"http:\/\/www.amis-musee-faience-quimper.fr\/index.php\/wp-json\/wp\/v2\/posts\/778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.amis-musee-faience-quimper.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.amis-musee-faience-quimper.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.amis-musee-faience-quimper.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.amis-musee-faience-quimper.fr\/index.php\/wp-json\/wp\/v2\/comments?post=778"}],"version-history":[{"count":8,"href":"http:\/\/www.amis-musee-faience-quimper.fr\/index.php\/wp-json\/wp\/v2\/posts\/778\/revisions"}],"predecessor-version":[{"id":797,"href":"http:\/\/www.amis-musee-faience-quimper.fr\/index.php\/wp-json\/wp\/v2\/posts\/778\/revisions\/797"}],"wp:attachment":[{"href":"http:\/\/www.amis-musee-faience-quimper.fr\/index.php\/wp-json\/wp\/v2\/media?parent=778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.amis-musee-faience-quimper.fr\/index.php\/wp-json\/wp\/v2\/categories?post=778"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.amis-musee-faience-quimper.fr\/index.php\/wp-json\/wp\/v2\/tags?post=778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}