{"id":4073,"date":"2020-08-08T17:43:27","date_gmt":"2020-08-08T15:43:27","guid":{"rendered":"http:\/\/www.amis-musee-faience-quimper.fr\/?p=4073"},"modified":"2020-08-08T17:43:35","modified_gmt":"2020-08-08T15:43:35","slug":"a-quimper-la-faience-revele-encore-des-tresors-le-telegramme","status":"publish","type":"post","link":"http:\/\/www.amis-musee-faience-quimper.fr\/index.php\/2020\/08\/08\/a-quimper-la-faience-revele-encore-des-tresors-le-telegramme\/","title":{"rendered":"\u00c0 Quimper, la fa\u00efence r\u00e9v\u00e8le encore des tr\u00e9sors (Le T\u00e9l\u00e9gramme)."},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"676\" height=\"452\" src=\"http:\/\/www.amis-musee-faience-quimper.fr\/wp-content\/uploads\/2020\/08\/Annic_Constanty.jpg\" alt=\"Annic Constany\" class=\"wp-image-4075\" srcset=\"http:\/\/www.amis-musee-faience-quimper.fr\/wp-content\/uploads\/2020\/08\/Annic_Constanty.jpg 676w, http:\/\/www.amis-musee-faience-quimper.fr\/wp-content\/uploads\/2020\/08\/Annic_Constanty-300x201.jpg 300w, http:\/\/www.amis-musee-faience-quimper.fr\/wp-content\/uploads\/2020\/08\/Annic_Constanty-449x300.jpg 449w\" sizes=\"auto, (max-width: 676px) 100vw, 676px\" \/><figcaption>Les amis du mus\u00e9e de la fa\u00efence ont renseign\u00e9 une quarantaine de propri\u00e9taires, ce samedi.<\/figcaption><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><em>Invit\u00e9s chaque ann\u00e9e \u00e0 pr\u00e9senter leurs pi\u00e8ces, les particuliers se sont press\u00e9s, ce samedi dans la cour du mus\u00e9e de la fa\u00efence. L\u2019occasion de r\u00e9v\u00e9ler quelques tr\u00e9sors.<\/em><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Des pi\u00e8ces de vaisselles chin\u00e9es \u00e0 un troc et puces, des plats et autres sculptures transmises de g\u00e9n\u00e9ration en g\u00e9n\u00e9ration ou trouv\u00e9es dans un grenier. Masqu\u00e9s pour cause de crise sanitaire, une quarantaine de collectionneurs et autres h\u00e9ritiers de pi\u00e8ces de fa\u00efences de Quimper se sont relay\u00e9s dans la cour du mus\u00e9e de Locmaria, ce samedi, pour conna\u00eetre l\u2019histoire de leurs biens et souvent avoir une id\u00e9e de leur valeur.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>\u00ab\u00a0C\u2019est notre r\u00f4le\u00a0\u00bb<\/strong><\/em>, souligne J\u00e9r\u00e9my Varoquier, l\u2019assistant principal du mus\u00e9e. En l\u2019absence de Bernard Verlingue, le conservateur des lieux, ce sont les amis du mus\u00e9e qui ont orient\u00e9 les propri\u00e9taires de pi\u00e8ces de fa\u00efence.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Du Quimper du XVIIIe&nbsp;si\u00e8cle&nbsp;?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Tout au long de la matin\u00e9e, pr\u00e8s de 200 pi\u00e8ces sont ainsi pass\u00e9es entre les mains de ces fins connaisseurs. Beaucoup de vaisselle. Mais parfois quelques belles pi\u00e8ces comme ce couple de sonneurs. Son propri\u00e9taire est reparti avec un pr\u00e9cieux conseil en poche\u00a0: le num\u00e9ro de t\u00e9l\u00e9phone d\u2019un restaurateur quimp\u00e9rois. Au-del\u00e0 du renseignement, l\u2019objectif, pour le mus\u00e9e quimp\u00e9rois, est <em><strong>\u00ab\u00a0d\u2019\u00e9viter la dispersion des pi\u00e8ces et de pr\u00e9server\u00a0\u00bb<\/strong><\/em> ce patrimoine.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>\u00ab\u00a0Au fur et \u00e0 mesure, le conservateur pensait que \u00e7a allait se tarir. Mais nous faisons des d\u00e9couvertes tous les ans\u00a0\u00bb<\/strong><\/em>, se r\u00e9jouit J\u00e9r\u00e9my Varoquier. Outre plusieurs pi\u00e8ces d\u2019artistes &#8211; Micheau Vernez, Nicot, Fouillen, Keraluc &#8211;\u00a0les amis du mus\u00e9e ont eu de la fa\u00efence du XVIIIe\u00a0si\u00e8cle entre les mains, ce samedi. <em><strong>\u00ab\u00a0Il pourrait s\u2019agir de \u00ab\u00a0vieux Quimper\u00a0\u00bb. Cela reste \u00e0 confirmer parce qu\u2019il n\u2019y avait pas de signatures \u00e0 l\u2019\u00e9poque\u00a0\u00bb<\/strong><\/em>. Des \u0153uvres historiques susceptibles d\u2019entrer dans les collections du mus\u00e9e de Locmaria. Pas par le biais d\u2019achats. Le lieu n\u2019en a pas les moyens. Mais par l\u2019interm\u00e9diaire de dons. Les pi\u00e8ces dat\u00e9es de 1769 pourraient ainsi rejoindre le mus\u00e9e.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><em>Publi\u00e9 le 8 ao\u00fbt 2020 par Jean Le Borgne &#8211; Le T\u00e9l\u00e9gramme \u00a9<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Invit\u00e9s chaque ann\u00e9e \u00e0 pr\u00e9senter leurs pi\u00e8ces, les particuliers se sont press\u00e9s, ce samedi dans la cour du mus\u00e9e de la fa\u00efence. L\u2019occasion de r\u00e9v\u00e9ler quelques tr\u00e9sors. Des pi\u00e8ces de vaisselles chin\u00e9es \u00e0 un troc et puces, des plats et &hellip; <a href=\"http:\/\/www.amis-musee-faience-quimper.fr\/index.php\/2020\/08\/08\/a-quimper-la-faience-revele-encore-des-tresors-le-telegramme\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[17],"tags":[936,240,1034,7,1035,821,461,1036,12,23,14,15],"class_list":["post-4073","post","type-post","status-publish","format-standard","hentry","category-actualites","tag-936","tag-annic-constanty","tag-conseil","tag-faience","tag-information","tag-jean-le-borgne","tag-jeremy-varoquier","tag-matinee","tag-musee","tag-quimper","tag-telegramme","tag-verlingue"],"jetpack_publicize_connections":[],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8tKLp-13H","_links":{"self":[{"href":"http:\/\/www.amis-musee-faience-quimper.fr\/index.php\/wp-json\/wp\/v2\/posts\/4073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.amis-musee-faience-quimper.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.amis-musee-faience-quimper.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.amis-musee-faience-quimper.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.amis-musee-faience-quimper.fr\/index.php\/wp-json\/wp\/v2\/comments?post=4073"}],"version-history":[{"count":3,"href":"http:\/\/www.amis-musee-faience-quimper.fr\/index.php\/wp-json\/wp\/v2\/posts\/4073\/revisions"}],"predecessor-version":[{"id":4077,"href":"http:\/\/www.amis-musee-faience-quimper.fr\/index.php\/wp-json\/wp\/v2\/posts\/4073\/revisions\/4077"}],"wp:attachment":[{"href":"http:\/\/www.amis-musee-faience-quimper.fr\/index.php\/wp-json\/wp\/v2\/media?parent=4073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.amis-musee-faience-quimper.fr\/index.php\/wp-json\/wp\/v2\/categories?post=4073"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.amis-musee-faience-quimper.fr\/index.php\/wp-json\/wp\/v2\/tags?post=4073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}